{"id":293807,"date":"2025-01-03T05:06:20","date_gmt":"2025-01-03T05:06:20","guid":{"rendered":"https:\/\/verdant-pillar.flywheelstaging.com\/product\/curso-en-linea-especializacion-profesional-certificada-en-habilidades-academicas-avanzadas-de-expresion-oral-y-auditiva-de-la-universidad-de-california-irvine\/"},"modified":"2025-01-03T05:06:20","modified_gmt":"2025-01-03T05:06:20","slug":"curso-en-linea-especializacion-profesional-certificada-en-habilidades-academicas-avanzadas-de-expresion-oral-y-auditiva-de-la-universidad-de-california-irvine","status":"publish","type":"product","link":"https:\/\/globalfinanceschool.com\/es\/product\/curso-en-linea-especializacion-profesional-certificada-en-habilidades-academicas-avanzadas-de-expresion-oral-y-auditiva-de-la-universidad-de-california-irvine\/","title":{"rendered":"Curso en l\u00ednea: especializaci\u00f3n profesional certificada en habilidades acad\u00e9micas avanzadas de expresi\u00f3n oral y auditiva de la Universidad de California, Irvine"},"content":{"rendered":"<ul>\n<li>Un estudiante de colegio o universidad<\/li>\n<li>profesora de ingles<\/li>\n<li>Facilitador de grupos de discusi\u00f3n.<\/li>\n<li>Un profesor en la academia.<\/li>\n<li>Experto en formaci\u00f3n<\/li>\n<li>director de programas educativos<\/li>\n<li>Una gu\u00eda para mejorar las habilidades ling\u00fc\u00edsticas.<\/li>\n<li>Desarrollador de contenidos acad\u00e9micos<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mejore sus habilidades para hablar y escuchar en ingl\u00e9s acad\u00e9mico. Aprenda a hablar y escuchar de forma m\u00e1s eficaz. <\/p>\n","protected":false},"featured_media":270077,"template":"","meta":[],"product_brand":[],"product_cat":[14592,13931],"product_tag":[14593,13935,13938],"class_list":["post-293807","product","type-product","status-publish","has-post-thumbnail","product_cat-aprender-ingles","product_cat-coursera-es","product_tag-aprendizaje-de-idiomas","product_tag-coursera-es","product_tag-especializacion-profesional","pa_author-2-universidad-de-california-irvine","pa_kind-especializacion-profesional","pa_level-nivel-intermedio","first","instock","product-type-external"],"_links":{"self":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/293807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/293807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media\/270077"}],"wp:attachment":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media?parent=293807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_brand?post=293807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_cat?post=293807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_tag?post=293807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}