{"id":279560,"date":"2024-12-11T01:30:18","date_gmt":"2024-12-21T11:13:44","guid":{"rendered":"https:\/\/gfssite.local\/product\/curso-en-linea-certificado-profesional-certificado-en-desarrollo-de-software-en-toda-la-pila-de-ibm\/"},"modified":"2025-01-03T02:31:53","modified_gmt":"2025-01-03T02:31:53","slug":"curso-en-linea-certificado-profesional-certificado-en-desarrollo-de-software-en-toda-la-pila-de-ibm","status":"publish","type":"product","link":"https:\/\/globalfinanceschool.com\/es\/product\/curso-en-linea-certificado-profesional-certificado-en-desarrollo-de-software-en-toda-la-pila-de-ibm\/","title":{"rendered":"Curso en l\u00ednea: certificado profesional certificado en desarrollo de software en toda la pila de IBM"},"content":{"rendered":"<ul>\n<li>desarrollador de software<\/li>\n<li>Desarrollador Full Stack<\/li>\n<li>Desarrollador de aplicaciones en la nube<\/li>\n<li>Desarrollador front-end<\/li>\n<li>Desarrollador de back-end<\/li>\n<li>Desarrollador con conocimientos de DevOps<\/li>\n<li>Desarrollador con conocimientos de Docker y Kubernetes<\/li>\n<li>Desarrollador con conocimientos de NoSQL<\/li>\n<li>Un desarrollador con conocimientos de Python y Django.<\/li>\n<li>Desarrollador con conocimientos de React<\/li>\n<li>Desarrollador con conocimientos de Node.js<\/li>\n<li>Un desarrollador con conocimientos de seguridad de aplicaciones.<\/li>\n<li>Un desarrollador con conocimientos de microservicios.<\/li>\n<li>Un desarrollador con conocimientos de inform\u00e1tica sin servidor.<\/li>\n<li>Un desarrollador con conocimientos de CI\/CD<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Prep\u00e1rese para una carrera como desarrollador de Paul Streck. Adquiera las habilidades necesarias que lo preparar\u00e1n para el trabajo (incluidas habilidades esenciales de IA) para una carrera en demanda. Obtenga un certificado de IBM.  <\/p>\n","protected":false},"featured_media":266493,"template":"","meta":[],"product_brand":[],"product_cat":[15317,13931],"product_tag":[16211,13935,16340,15453,13943,14578,14176],"class_list":["post-279560","product","type-product","status-publish","has-post-thumbnail","product_cat-computacion-en-la-nube-es","product_cat-coursera-es","product_tag-certificado-profesional","product_tag-coursera-es","product_tag-cursos","product_tag-desarrollador-de-aplicaciones-en-la-nube","product_tag-desarrollador-de-software","product_tag-desarrollador-full-stack","product_tag-tecnologias-de-la-informacion","pa_author-2-ibm-es","pa_kind-certificado-profesional","pa_level-a-partir-de","first","instock","product-type-external"],"_links":{"self":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/279560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/279560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media\/266493"}],"wp:attachment":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media?parent=279560"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_brand?post=279560"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_cat?post=279560"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_tag?post=279560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}