{"id":276978,"date":"2024-12-11T01:32:56","date_gmt":"2024-12-21T06:35:19","guid":{"rendered":"https:\/\/gfssite.local\/product\/curso-online-certificado-profesional-certificado-en-diseno-ux-de-google\/"},"modified":"2025-01-03T02:08:06","modified_gmt":"2025-01-03T02:08:06","slug":"curso-online-certificado-profesional-certificado-en-diseno-ux-de-google","status":"publish","type":"product","link":"https:\/\/globalfinanceschool.com\/es\/product\/curso-online-certificado-profesional-certificado-en-diseno-ux-de-google\/","title":{"rendered":"Curso online &#8211; certificado profesional certificado en Dise\u00f1o UX de Google"},"content":{"rendered":"<ul>\n<li>Dise\u00f1adores de experiencia de usuario (UX)<\/li>\n<li>gerentes de producto<\/li>\n<li>Dise\u00f1adores de interacci\u00f3n<\/li>\n<li>Desarrolladores de aplicaciones<\/li>\n<li>Analistas de experiencia de usuario<\/li>\n<li>investigadores de experiencia de usuario<\/li>\n<li>Dise\u00f1adores gr\u00e1ficos con especializaci\u00f3n en UX<\/li>\n<li>Expertos en accesibilidad digital<\/li>\n<li>Responsables de proyectos en el campo de la tecnolog\u00eda.<\/li>\n<li>Consultores en el campo de la experiencia de usuario.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tu camino hacia una carrera en dise\u00f1o UX. Durante este programa aprender\u00e1s las habilidades necesarias para empezar a trabajar en menos de seis meses. <\/p>\n","protected":false},"featured_media":270777,"template":"","meta":[],"product_brand":[],"product_cat":[13931,15922],"product_tag":[16211,13940,13935,15217],"class_list":["post-276978","product","type-product","status-publish","has-post-thumbnail","product_cat-coursera-es","product_cat-diseno-y-producto-es","product_tag-certificado-profesional","product_tag-ciencias-de-la-computacion","product_tag-coursera-es","product_tag-gerentes-de-producto","pa_author-2-google-es","pa_kind-certificado-profesional","pa_level-a-partir-de","first","instock","product-type-external"],"_links":{"self":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/276978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product\/276978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media\/270777"}],"wp:attachment":[{"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/media?parent=276978"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_brand?post=276978"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_cat?post=276978"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/globalfinanceschool.com\/es\/wp-json\/wp\/v2\/product_tag?post=276978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}